{"id":7815,"date":"2026-05-13T14:29:39","date_gmt":"2026-05-13T14:29:39","guid":{"rendered":"https:\/\/urbanizacionelbosque.org\/?p=7815"},"modified":"2026-05-13T14:29:42","modified_gmt":"2026-05-13T14:29:42","slug":"el-tribunal-superior-de-justicia-de-madrid-desestima-otro-recurso-interpuesto-por-la-anterior-junta-de-gobierno-de-la-entidad-urbanistica-el-bosque","status":"publish","type":"post","link":"https:\/\/urbanizacionelbosque.org\/index.php\/2026\/05\/13\/el-tribunal-superior-de-justicia-de-madrid-desestima-otro-recurso-interpuesto-por-la-anterior-junta-de-gobierno-de-la-entidad-urbanistica-el-bosque\/","title":{"rendered":"El Tribunal Superior de Justicia de Madrid desestima otro recurso interpuesto por la anterior Junta de Gobierno de la Entidad Urban\u00edstica El Bosque"},"content":{"rendered":"\n<p><strong>El Tribunal Superior de Justicia de Madrid desestima otro recurso interpuesto por la anterior Junta de Gobierno de la Entidad Urban\u00edstica El Bosque<\/strong><\/p>\n\n\n\n<p>El Tribunal Superior de Justicia de Madrid ha dictado la Sentencia n\u00ba 435\/2026, de fecha 4 de mayo de 2026, por la que desestima el recurso de apelaci\u00f3n interpuesto por la anterior Junta de Gobierno de la Entidad Urban\u00edstica El Bosque contra el Auto dictado por el Juzgado de lo Contencioso-Administrativo n\u00ba 9 de Madrid, relativo a la pieza de medidas cautelares del procedimiento sobre las elecciones celebradas en la Entidad el 20 de noviembre de 2024.<\/p>\n\n\n\n<p>La resoluci\u00f3n judicial confirma as\u00ed la negativa de suspender el Decreto municipal que anul\u00f3 las elecciones celebradas en la Entidad Urban\u00edstica El Bosque el 20 de noviembre de 2024 y la constituci\u00f3n de la Junta de Gobierno surgida de dicho proceso electoral.<\/p>\n\n\n\n<p>El Tribunal rechaza los argumentos planteados por la anterior Junta de Gobierno y concluye que no concurren los requisitos necesarios para adoptar las medidas cautelares solicitadas. En este sentido, considera que no se acredita un perjuicio y recuerda que las Entidades Urban\u00edsticas ejercen funciones p\u00fablicas bajo supervisi\u00f3n municipal.<\/p>\n\n\n\n<p>Asimismo, el Tribunal impone las costas procesales a la parte apelante de 2.000 euros m\u00e1s IVA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Tribunal Superior de Justicia de Madrid desestima otro recurso interpuesto por la anterior Junta de Gobierno de la Entidad Urban\u00edstica El Bosque El Tribunal Superior de Justicia de Madrid ha dictado la Sentencia n\u00ba 435\/2026, de fecha 4 de mayo de 2026, por la que desestima el recurso de apelaci\u00f3n interpuesto por la anterior [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6095,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"795","footnotes":""},"categories":[36,24,34],"tags":[],"class_list":["post-7815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuntamiento-informacion-municipal-sobre-la-entidad","category-notas-informativas","category-portada"],"_links":{"self":[{"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/posts\/7815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/comments?post=7815"}],"version-history":[{"count":1,"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/posts\/7815\/revisions"}],"predecessor-version":[{"id":7816,"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/posts\/7815\/revisions\/7816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/media?parent=7815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/categories?post=7815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbanizacionelbosque.org\/index.php\/wp-json\/wp\/v2\/tags?post=7815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}